{"id":38372,"date":"2026-09-02T05:27:51","date_gmt":"2026-09-02T05:27:51","guid":{"rendered":"https:\/\/expresorgv.online\/home\/?p=38372"},"modified":"2026-09-02T05:27:52","modified_gmt":"2026-09-02T05:27:52","slug":"tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo","status":"publish","type":"post","link":"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/","title":{"rendered":"Tras 25 a\u00f1os de construcci\u00f3n, finalizan una de las obras m\u00e1s importantes de nuevo Laredo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Despu\u00e9s de <strong>permanecer <\/strong>pendiente durante m\u00e1s de 25 a\u00f1os, fue concluido el <strong>segundo cuerpo de la carretera MEX II<\/strong> y su <strong>puente vehicular<\/strong>, obra estrat\u00e9gica para agilizar el tr\u00e1nsito de carga y mejorar la conexi\u00f3n hacia el <strong>Puente del Comercio Mundial<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto represent\u00f3 una <strong>inversi\u00f3n municipal <\/strong>de 283 millones 220 mil pesos y forma parte de las obras que la <strong>alcaldesa Carmen Lilia Canturosas Villarreal <\/strong>destaca rumbo a su segundo informe de gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para desarrollar la <strong>infraestructura <\/strong>fue necesaria la autorizaci\u00f3n de la Secretar\u00eda de Infraestructura, Comunicaciones y Transportes (<strong>SICT<\/strong>), debido a que los trabajos se realizaron en una zona de competencia federal, aunque los recursos fueron aportados por el <strong>municipio<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Modernizaci\u00f3n vial tras 25 a\u00f1os de espera en Tamaulipas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La importancia de la<strong> MEX II <\/strong>radica en el volumen de transporte pesado que <strong>concentra diariamente<\/strong>. De acuerdo con informaci\u00f3n del gobierno municipal, por este <strong>libramiento <\/strong>circulan m\u00e1s de 16 mil unidades de carga al d\u00eda con mercanc\u00edas de importaci\u00f3n y exportaci\u00f3n entre <strong>M\u00e9xico <\/strong>y <strong>Estados Unidos<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La obra comprende mil 600 metros lineales de <strong>carretera<\/strong>, adem\u00e1s de un <strong>puente vehicular <\/strong>de 944.72 metros de longitud, <strong>rampas <\/strong>de <strong>acceso <\/strong>y una superestructura de 67.91 metros. La vialidad cuenta con un ancho de 14.15 metros y <strong>parapetos <\/strong>de <strong>seguridad<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la ampliaci\u00f3n se busca reducir los tiempos de <strong>traslado<\/strong>, brindar mayor seguridad a los operadores y mejorar la fluidez de los veh\u00edculos que se dirigen hacia el <strong>Puente <\/strong>del <strong>Comercio<\/strong> <strong>Mundial<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La obra conectar\u00e1 m\u00e1s a Tamaulipas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>administraci\u00f3n municipal <\/strong>se\u00f1al\u00f3 que la obra pudo concretarse mediante coordinaci\u00f3n con los <strong>gobiernos federal <\/strong>y <strong>estatal<\/strong>, despu\u00e9s de d\u00e9cadas en las que el crecimiento del comercio exterior y del tr\u00e1nsito pesado increment\u00f3 la necesidad de ampliar esta v\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nuevo Laredo <\/strong>concentra uno de los principales <strong>cruces terrestres <\/strong>de mercanc\u00edas entre <strong>M\u00e9xico <\/strong>y <strong>Estados Unidos<\/strong>, por lo que la modernizaci\u00f3n de sus accesos carreteros tiene impacto no solamente en la movilidad local, sino tambi\u00e9n en las cadenas log\u00edsticas vinculadas al comercio internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La conclusi\u00f3n del <strong>segundo cuerpo <\/strong>de la<strong> MEX II<\/strong> representa as\u00ed una de las principales obras de <strong>infraestructura <\/strong>de la actual <strong>administraci\u00f3n municipal <\/strong>y busca responder al crecimiento que mantiene Nuevo Laredo como uno de los principales puntos log\u00edsticos de la frontera norte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de permanecer pendiente durante m\u00e1s de 25 a\u00f1os, fue concluido el segundo cuerpo de la carretera MEX II y su puente vehicular, obra estrat\u00e9gica para agilizar el tr\u00e1nsito de carga y mejorar la conexi\u00f3n hacia el Puente del Comercio Mundial. El proyecto represent\u00f3 una inversi\u00f3n municipal de 283 millones 220 mil pesos y forma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":38355,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-38372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-n-laredo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tras 25 a\u00f1os de construcci\u00f3n, finalizan una de las obras m\u00e1s importantes de nuevo Laredo -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tras 25 a\u00f1os de construcci\u00f3n, finalizan una de las obras m\u00e1s importantes de nuevo Laredo\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de permanecer pendiente durante m\u00e1s de 25 a\u00f1os, fue concluido el segundo cuerpo de la carretera MEX II y su puente vehicular, obra estrat\u00e9gica para agilizar el tr\u00e1nsito de carga y mejorar la conexi\u00f3n hacia el Puente del Comercio Mundial. El proyecto represent\u00f3 una inversi\u00f3n municipal de 283 millones 220 mil pesos y forma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T05:27:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T05:27:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expresorgv.online\/home\/wp-content\/uploads\/2026\/09\/02092026ConstruccionnLaredo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"expreso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"expreso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/\"},\"author\":{\"name\":\"expreso\",\"@id\":\"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2\"},\"headline\":\"Tras 25 a\u00f1os de construcci\u00f3n, finalizan una de las obras m\u00e1s importantes de nuevo Laredo\",\"datePublished\":\"2026-09-02T05:27:51+00:00\",\"dateModified\":\"2026-09-02T05:27:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/\"},\"wordCount\":417,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/09\/02092026ConstruccionnLaredo.png?fit=540%2C300&ssl=1\",\"articleSection\":[\"N. LAREDO\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/\",\"url\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/\",\"name\":\"Tras 25 a\u00f1os de construcci\u00f3n, finalizan una de las obras m\u00e1s importantes de nuevo Laredo -\",\"isPartOf\":{\"@id\":\"https:\/\/expresorgv.online\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/09\/02092026ConstruccionnLaredo.png?fit=540%2C300&ssl=1\",\"datePublished\":\"2026-09-02T05:27:51+00:00\",\"dateModified\":\"2026-09-02T05:27:52+00:00\",\"author\":{\"@id\":\"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/09\/02092026ConstruccionnLaredo.png?fit=540%2C300&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/09\/02092026ConstruccionnLaredo.png?fit=540%2C300&ssl=1\",\"width\":540,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/expresorgv.online\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tras 25 a\u00f1os de construcci\u00f3n, finalizan una de las obras m\u00e1s importantes de nuevo Laredo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/expresorgv.online\/home\/#website\",\"url\":\"https:\/\/expresorgv.online\/home\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/expresorgv.online\/home\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2\",\"name\":\"expreso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g\",\"caption\":\"expreso\"},\"url\":\"https:\/\/expresorgv.online\/home\/blog\/author\/expreso\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tras 25 a\u00f1os de construcci\u00f3n, finalizan una de las obras m\u00e1s importantes de nuevo Laredo -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/","og_locale":"es_ES","og_type":"article","og_title":"Tras 25 a\u00f1os de construcci\u00f3n, finalizan una de las obras m\u00e1s importantes de nuevo Laredo","og_description":"Despu\u00e9s de permanecer pendiente durante m\u00e1s de 25 a\u00f1os, fue concluido el segundo cuerpo de la carretera MEX II y su puente vehicular, obra estrat\u00e9gica para agilizar el tr\u00e1nsito de carga y mejorar la conexi\u00f3n hacia el Puente del Comercio Mundial. El proyecto represent\u00f3 una inversi\u00f3n municipal de 283 millones 220 mil pesos y forma [&hellip;]","og_url":"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/","article_published_time":"2026-09-02T05:27:51+00:00","article_modified_time":"2026-09-02T05:27:52+00:00","og_image":[{"width":540,"height":300,"url":"https:\/\/expresorgv.online\/home\/wp-content\/uploads\/2026\/09\/02092026ConstruccionnLaredo.png","type":"image\/png"}],"author":"expreso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"expreso","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#article","isPartOf":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/"},"author":{"name":"expreso","@id":"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2"},"headline":"Tras 25 a\u00f1os de construcci\u00f3n, finalizan una de las obras m\u00e1s importantes de nuevo Laredo","datePublished":"2026-09-02T05:27:51+00:00","dateModified":"2026-09-02T05:27:52+00:00","mainEntityOfPage":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/"},"wordCount":417,"commentCount":0,"image":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/09\/02092026ConstruccionnLaredo.png?fit=540%2C300&ssl=1","articleSection":["N. LAREDO"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/","url":"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/","name":"Tras 25 a\u00f1os de construcci\u00f3n, finalizan una de las obras m\u00e1s importantes de nuevo Laredo -","isPartOf":{"@id":"https:\/\/expresorgv.online\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#primaryimage"},"image":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/09\/02092026ConstruccionnLaredo.png?fit=540%2C300&ssl=1","datePublished":"2026-09-02T05:27:51+00:00","dateModified":"2026-09-02T05:27:52+00:00","author":{"@id":"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2"},"breadcrumb":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#primaryimage","url":"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/09\/02092026ConstruccionnLaredo.png?fit=540%2C300&ssl=1","contentUrl":"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/09\/02092026ConstruccionnLaredo.png?fit=540%2C300&ssl=1","width":540,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/09\/02\/tras-25-anos-de-construccion-finalizan-una-de-las-obras-mas-importantes-de-nuevo-laredo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expresorgv.online\/home\/"},{"@type":"ListItem","position":2,"name":"Tras 25 a\u00f1os de construcci\u00f3n, finalizan una de las obras m\u00e1s importantes de nuevo Laredo"}]},{"@type":"WebSite","@id":"https:\/\/expresorgv.online\/home\/#website","url":"https:\/\/expresorgv.online\/home\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expresorgv.online\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2","name":"expreso","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g","caption":"expreso"},"url":"https:\/\/expresorgv.online\/home\/blog\/author\/expreso\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/09\/02092026ConstruccionnLaredo.png?fit=540%2C300&ssl=1","_links":{"self":[{"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/posts\/38372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/comments?post=38372"}],"version-history":[{"count":1,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/posts\/38372\/revisions"}],"predecessor-version":[{"id":38373,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/posts\/38372\/revisions\/38373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/media\/38355"}],"wp:attachment":[{"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/media?parent=38372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/categories?post=38372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/tags?post=38372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}