{"id":36752,"date":"2026-07-15T05:14:22","date_gmt":"2026-07-15T05:14:22","guid":{"rendered":"https:\/\/expresorgv.online\/home\/?p=36752"},"modified":"2026-07-15T05:14:23","modified_gmt":"2026-07-15T05:14:23","slug":"renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados","status":"publish","type":"post","link":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/","title":{"rendered":"Renuncia Ulises Lara a la FGR tras rev\u00e9s de la fiscal\u00eda en Caso Agronitrogenados"},"content":{"rendered":"\n<p><strong>Ulises Lara L\u00f3pez<\/strong> present\u00f3 su renuncia a la <strong>Fiscal\u00eda Especial en Investigaci\u00f3n de Asuntos Relevantes de la Fiscal\u00eda<\/strong> General de la Rep\u00fablica (FGR).<\/p>\n\n\n\n<p>Fuentes oficiales atribuyeron su renuncia a \u201cmotivos personales\u201d, pero dentro de la propia fiscal\u00eda se menciona que su salida tambi\u00e9n tiene relaci\u00f3n con el rev\u00e9s que sufri\u00f3 la FGR con la libertad condicional que logr\u00f3 Gilda Susana Lozoya Austin, <strong>hermana del ex director de Pemex, Emilio Lozoya<\/strong>, en el proceso penal que se le sigue por el Caso Agronitrogenados.<\/p>\n\n\n\n<p>La FGR se\u00f1al\u00f3 que tras la renuncia de Ulises Lara, <strong>la Fiscal General de la Rep\u00fablica, Ernestina Godoy<\/strong>, har\u00e1 un nuevo nombramiento en la cartera vac\u00eda.<br><a href=\"https:\/\/editorial.aristeguinoticias.com\/wp-content\/uploads\/2025\/05\/ulises-lara-nuevo-delegado-fgr-morelos-2-16062025.jpg\"><\/a><\/p>\n\n\n\n<p>Antes de ocupar su cargo como vocero de la FGR, Ulises Lara se desempe\u00f1\u00f3 como <strong>fiscal de Morelos y encargado de la Fiscal\u00eda capitalina<\/strong> en sustituci\u00f3n de Ernestina Godoy.<\/p>\n\n\n\n<p>Licenciado en Sociolog\u00eda por la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM), obtuvo un doctorado en Derecho por una instituci\u00f3n privada previo a ser fiscal encargado de la Fiscal\u00eda General de Justicia de la Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p>Previamente, fungi\u00f3 como Director General de Dise\u00f1o de Estrategias y responsable de la Unidad de Transici\u00f3n de la entonces Procuradur\u00eda capitalina.<\/p>\n\n\n\n<p>Tambi\u00e9n es p\u00fablico que Ulises Lara estuvo casado con la ex ministra Lenia Batres Guadarrama.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ulises Lara L\u00f3pez present\u00f3 su renuncia a la Fiscal\u00eda Especial en Investigaci\u00f3n de Asuntos Relevantes de la Fiscal\u00eda General de la Rep\u00fablica (FGR). Fuentes oficiales atribuyeron su renuncia a \u201cmotivos personales\u201d, pero dentro de la propia fiscal\u00eda se menciona que su salida tambi\u00e9n tiene relaci\u00f3n con el rev\u00e9s que sufri\u00f3 la FGR con la libertad [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":36746,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-36752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Renuncia Ulises Lara a la FGR tras rev\u00e9s de la fiscal\u00eda en Caso Agronitrogenados -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renuncia Ulises Lara a la FGR tras rev\u00e9s de la fiscal\u00eda en Caso Agronitrogenados\" \/>\n<meta property=\"og:description\" content=\"Ulises Lara L\u00f3pez present\u00f3 su renuncia a la Fiscal\u00eda Especial en Investigaci\u00f3n de Asuntos Relevantes de la Fiscal\u00eda General de la Rep\u00fablica (FGR). Fuentes oficiales atribuyeron su renuncia a \u201cmotivos personales\u201d, pero dentro de la propia fiscal\u00eda se menciona que su salida tambi\u00e9n tiene relaci\u00f3n con el rev\u00e9s que sufri\u00f3 la FGR con la libertad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T05:14:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T05:14:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026UlisesLara.png\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"expreso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"expreso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/\"},\"author\":{\"name\":\"expreso\",\"@id\":\"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2\"},\"headline\":\"Renuncia Ulises Lara a la FGR tras rev\u00e9s de la fiscal\u00eda en Caso Agronitrogenados\",\"datePublished\":\"2026-07-15T05:14:22+00:00\",\"dateModified\":\"2026-07-15T05:14:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/\"},\"wordCount\":250,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026UlisesLara.png?fit=540%2C300&ssl=1\",\"articleSection\":[\"NACIONAL\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/\",\"url\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/\",\"name\":\"Renuncia Ulises Lara a la FGR tras rev\u00e9s de la fiscal\u00eda en Caso Agronitrogenados -\",\"isPartOf\":{\"@id\":\"https:\/\/expresorgv.online\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026UlisesLara.png?fit=540%2C300&ssl=1\",\"datePublished\":\"2026-07-15T05:14:22+00:00\",\"dateModified\":\"2026-07-15T05:14:23+00:00\",\"author\":{\"@id\":\"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026UlisesLara.png?fit=540%2C300&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026UlisesLara.png?fit=540%2C300&ssl=1\",\"width\":540,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/expresorgv.online\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renuncia Ulises Lara a la FGR tras rev\u00e9s de la fiscal\u00eda en Caso Agronitrogenados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/expresorgv.online\/home\/#website\",\"url\":\"https:\/\/expresorgv.online\/home\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/expresorgv.online\/home\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2\",\"name\":\"expreso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g\",\"caption\":\"expreso\"},\"url\":\"https:\/\/expresorgv.online\/home\/blog\/author\/expreso\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Renuncia Ulises Lara a la FGR tras rev\u00e9s de la fiscal\u00eda en Caso Agronitrogenados -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/","og_locale":"es_ES","og_type":"article","og_title":"Renuncia Ulises Lara a la FGR tras rev\u00e9s de la fiscal\u00eda en Caso Agronitrogenados","og_description":"Ulises Lara L\u00f3pez present\u00f3 su renuncia a la Fiscal\u00eda Especial en Investigaci\u00f3n de Asuntos Relevantes de la Fiscal\u00eda General de la Rep\u00fablica (FGR). Fuentes oficiales atribuyeron su renuncia a \u201cmotivos personales\u201d, pero dentro de la propia fiscal\u00eda se menciona que su salida tambi\u00e9n tiene relaci\u00f3n con el rev\u00e9s que sufri\u00f3 la FGR con la libertad [&hellip;]","og_url":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/","article_published_time":"2026-07-15T05:14:22+00:00","article_modified_time":"2026-07-15T05:14:23+00:00","og_image":[{"width":540,"height":300,"url":"https:\/\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026UlisesLara.png","type":"image\/png"}],"author":"expreso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"expreso","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#article","isPartOf":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/"},"author":{"name":"expreso","@id":"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2"},"headline":"Renuncia Ulises Lara a la FGR tras rev\u00e9s de la fiscal\u00eda en Caso Agronitrogenados","datePublished":"2026-07-15T05:14:22+00:00","dateModified":"2026-07-15T05:14:23+00:00","mainEntityOfPage":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/"},"wordCount":250,"commentCount":0,"image":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026UlisesLara.png?fit=540%2C300&ssl=1","articleSection":["NACIONAL"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/","url":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/","name":"Renuncia Ulises Lara a la FGR tras rev\u00e9s de la fiscal\u00eda en Caso Agronitrogenados -","isPartOf":{"@id":"https:\/\/expresorgv.online\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#primaryimage"},"image":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026UlisesLara.png?fit=540%2C300&ssl=1","datePublished":"2026-07-15T05:14:22+00:00","dateModified":"2026-07-15T05:14:23+00:00","author":{"@id":"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2"},"breadcrumb":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#primaryimage","url":"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026UlisesLara.png?fit=540%2C300&ssl=1","contentUrl":"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026UlisesLara.png?fit=540%2C300&ssl=1","width":540,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/renuncia-ulises-lara-a-la-fgr-tras-reves-de-la-fiscalia-en-caso-agronitrogenados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expresorgv.online\/home\/"},{"@type":"ListItem","position":2,"name":"Renuncia Ulises Lara a la FGR tras rev\u00e9s de la fiscal\u00eda en Caso Agronitrogenados"}]},{"@type":"WebSite","@id":"https:\/\/expresorgv.online\/home\/#website","url":"https:\/\/expresorgv.online\/home\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expresorgv.online\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2","name":"expreso","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g","caption":"expreso"},"url":"https:\/\/expresorgv.online\/home\/blog\/author\/expreso\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026UlisesLara.png?fit=540%2C300&ssl=1","_links":{"self":[{"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/posts\/36752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/comments?post=36752"}],"version-history":[{"count":1,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/posts\/36752\/revisions"}],"predecessor-version":[{"id":36753,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/posts\/36752\/revisions\/36753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/media\/36746"}],"wp:attachment":[{"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/media?parent=36752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/categories?post=36752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/tags?post=36752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}