{"id":36748,"date":"2026-07-15T05:07:42","date_gmt":"2026-07-15T05:07:42","guid":{"rendered":"https:\/\/expresorgv.online\/home\/?p=36748"},"modified":"2026-07-15T05:07:43","modified_gmt":"2026-07-15T05:07:43","slug":"responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco","status":"publish","type":"post","link":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/","title":{"rendered":"Responde M\u00e9xico a la DEA: niega &#8216;conexi\u00f3n mortal&#8217; con el narco"},"content":{"rendered":"\n<p>El Gabinete de Seguridad de M\u00e9xico rechaz\u00f3 las declaraciones del administrador de la Administraci\u00f3n para el Control de Drogas de Estados Unidos (DEA), Terrance C. Cole, quien dijo que hay una \u2018conexi\u00f3n mortal\u2019 entre c\u00e1rteles y gobierno mexicano.<\/p>\n\n\n\n<p>En comunicado, el gobierno mexicano calific\u00f3 como \u201ccarentes de sustento\u201d las afirmaciones sobre una presunta <strong>conexi\u00f3n entre el Estado mexicano y las organizaciones del narcotr\u00e1fico<\/strong>. En un comunicado, sostuvo que los se\u00f1alamientos no corresponden con los resultados p\u00fablicos y verificables presentados por las autoridades mexicanas en el combate contra la delincuencia organizada.<\/p>\n\n\n\n<p>Como respuesta, el gobierno de M\u00e9xico defendi\u00f3 la Estrategia Nacional de Seguridad y afirm\u00f3 que se basa en una pol\u00edtica de \u201ccero impunidad\u201d. Indic\u00f3 que, desde el inicio de la actual administraci\u00f3n y hasta el 30 de junio de 2026, las autoridades<strong> detuvieron a 59 mil 582 personas<\/strong>, entre ellas presuntos l\u00edderes e integrantes de distintos grupos delictivos.<br><br>Asimismo, report\u00f3 el aseguramiento de <strong>31 mil 366 armas de fuego y 498 toneladas de drogas<\/strong>. Entre los resultados, destac\u00f3 el decomiso de 2 mil 363 kilogramos y 5 millones 546 mil 100 pastillas de fentanilo, as\u00ed como la inhabilitaci\u00f3n de 2 mil 627 laboratorios clandestinos.<\/p>\n\n\n\n<p>En relaci\u00f3n con los se\u00f1alamientos sobre una posible complicidad institucional, el comunicado destac\u00f3 los resultados de la <strong>Operaci\u00f3n Enjambre<\/strong>. De acuerdo con el Gobierno de M\u00e9xico, esa estrategia permiti\u00f3 procesar a m\u00e1s de 80 servidores y exservidores p\u00fablicos presuntamente vinculados con actividades delictivas, incluidos siete presidentes municipales en funciones. Las autoridades sostuvieron que estos resultados demuestran que \u201cno existe protecci\u00f3n para ninguna persona que incurra en conductas il\u00edcitas\u201d.<\/p>\n\n\n\n<p>El Gabinete de Seguridad tambi\u00e9n inform\u00f3 que la estrategia nacional contribuy\u00f3 a una reducci\u00f3n del 48 por ciento en el promedio diario de homicidios dolosos entre septiembre de 2024 y junio de 2026.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Respuesta a las declaraciones de la DEA<\/h2>\n\n\n\n<p>El pronunciamiento del gobierno de M\u00e9xico respondi\u00f3 al discurso que Terrance C. Cole pronunci\u00f3 el 13 de julio durante la inauguraci\u00f3n de la primera cumbre Fentanyl Free America. En ese evento, el administrador de la DEA afirm\u00f3 que la agencia dirigir\u00eda todos sus esfuerzos contra los narcotraficantes y sus facilitadores, y sostuvo que existe una <strong>\u201cconexi\u00f3n mortal entre las redes de los c\u00e1rteles y el Gobierno mexicano\u201d<\/strong>. Adem\u00e1s, asegur\u00f3 que ambas entidades \u201cson una y la misma\u201d.<br><br>Durante su intervenci\u00f3n, Cole tambi\u00e9n destac\u00f3 los resultados obtenidos por la DEA durante la administraci\u00f3n del presidente Donald J. Trump y del fiscal general Todd Blanche. Seg\u00fan el funcionario, la agencia incaut\u00f3 m\u00e1s de 568 millones de dosis potencialmente letales de fentanilo como parte de una estrategia orientada a priorizar la seguridad de Estados Unidos.<\/p>\n\n\n\n<p>En su posicionamiento, el gobierno de M\u00e9xico record\u00f3 que los mecanismos de cooperaci\u00f3n bilateral han permitido la detenci\u00f3n de diversos objetivos prioritarios requeridos por la justicia estadounidense. Finalmente, reiter\u00f3 su disposici\u00f3n para fortalecer el trabajo conjunto con Estados Unidos en el combate a las organizaciones criminales transnacionales, siempre bajo los principios de \u201crespeto a la soberan\u00eda, confianza mutua, responsabilidad compartida y coordinaci\u00f3n\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gabinete de Seguridad de M\u00e9xico rechaz\u00f3 las declaraciones del administrador de la Administraci\u00f3n para el Control de Drogas de Estados Unidos (DEA), Terrance C. Cole, quien dijo que hay una \u2018conexi\u00f3n mortal\u2019 entre c\u00e1rteles y gobierno mexicano. En comunicado, el gobierno mexicano calific\u00f3 como \u201ccarentes de sustento\u201d las afirmaciones sobre una presunta conexi\u00f3n entre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":36745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-36748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Responde M\u00e9xico a la DEA: niega &#039;conexi\u00f3n mortal&#039; con el narco -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Responde M\u00e9xico a la DEA: niega &#039;conexi\u00f3n mortal&#039; con el narco\" \/>\n<meta property=\"og:description\" content=\"El Gabinete de Seguridad de M\u00e9xico rechaz\u00f3 las declaraciones del administrador de la Administraci\u00f3n para el Control de Drogas de Estados Unidos (DEA), Terrance C. Cole, quien dijo que hay una \u2018conexi\u00f3n mortal\u2019 entre c\u00e1rteles y gobierno mexicano. En comunicado, el gobierno mexicano calific\u00f3 como \u201ccarentes de sustento\u201d las afirmaciones sobre una presunta conexi\u00f3n entre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T05:07:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T05:07:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026Sedena.png\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"expreso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"expreso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/\"},\"author\":{\"name\":\"expreso\",\"@id\":\"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2\"},\"headline\":\"Responde M\u00e9xico a la DEA: niega &#8216;conexi\u00f3n mortal&#8217; con el narco\",\"datePublished\":\"2026-07-15T05:07:42+00:00\",\"dateModified\":\"2026-07-15T05:07:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/\"},\"wordCount\":529,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026Sedena.png?fit=540%2C300&ssl=1\",\"articleSection\":[\"NACIONAL\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/\",\"url\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/\",\"name\":\"Responde M\u00e9xico a la DEA: niega 'conexi\u00f3n mortal' con el narco -\",\"isPartOf\":{\"@id\":\"https:\/\/expresorgv.online\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026Sedena.png?fit=540%2C300&ssl=1\",\"datePublished\":\"2026-07-15T05:07:42+00:00\",\"dateModified\":\"2026-07-15T05:07:43+00:00\",\"author\":{\"@id\":\"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026Sedena.png?fit=540%2C300&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026Sedena.png?fit=540%2C300&ssl=1\",\"width\":540,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/expresorgv.online\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Responde M\u00e9xico a la DEA: niega &#8216;conexi\u00f3n mortal&#8217; con el narco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/expresorgv.online\/home\/#website\",\"url\":\"https:\/\/expresorgv.online\/home\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/expresorgv.online\/home\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2\",\"name\":\"expreso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g\",\"caption\":\"expreso\"},\"url\":\"https:\/\/expresorgv.online\/home\/blog\/author\/expreso\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Responde M\u00e9xico a la DEA: niega 'conexi\u00f3n mortal' con el narco -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/","og_locale":"es_ES","og_type":"article","og_title":"Responde M\u00e9xico a la DEA: niega 'conexi\u00f3n mortal' con el narco","og_description":"El Gabinete de Seguridad de M\u00e9xico rechaz\u00f3 las declaraciones del administrador de la Administraci\u00f3n para el Control de Drogas de Estados Unidos (DEA), Terrance C. Cole, quien dijo que hay una \u2018conexi\u00f3n mortal\u2019 entre c\u00e1rteles y gobierno mexicano. En comunicado, el gobierno mexicano calific\u00f3 como \u201ccarentes de sustento\u201d las afirmaciones sobre una presunta conexi\u00f3n entre [&hellip;]","og_url":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/","article_published_time":"2026-07-15T05:07:42+00:00","article_modified_time":"2026-07-15T05:07:43+00:00","og_image":[{"width":540,"height":300,"url":"https:\/\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026Sedena.png","type":"image\/png"}],"author":"expreso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"expreso","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#article","isPartOf":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/"},"author":{"name":"expreso","@id":"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2"},"headline":"Responde M\u00e9xico a la DEA: niega &#8216;conexi\u00f3n mortal&#8217; con el narco","datePublished":"2026-07-15T05:07:42+00:00","dateModified":"2026-07-15T05:07:43+00:00","mainEntityOfPage":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/"},"wordCount":529,"commentCount":0,"image":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026Sedena.png?fit=540%2C300&ssl=1","articleSection":["NACIONAL"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/","url":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/","name":"Responde M\u00e9xico a la DEA: niega 'conexi\u00f3n mortal' con el narco -","isPartOf":{"@id":"https:\/\/expresorgv.online\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#primaryimage"},"image":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026Sedena.png?fit=540%2C300&ssl=1","datePublished":"2026-07-15T05:07:42+00:00","dateModified":"2026-07-15T05:07:43+00:00","author":{"@id":"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2"},"breadcrumb":{"@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#primaryimage","url":"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026Sedena.png?fit=540%2C300&ssl=1","contentUrl":"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026Sedena.png?fit=540%2C300&ssl=1","width":540,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/expresorgv.online\/home\/blog\/2026\/07\/15\/responde-mexico-a-la-dea-niega-conexion-mortal-con-el-narco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expresorgv.online\/home\/"},{"@type":"ListItem","position":2,"name":"Responde M\u00e9xico a la DEA: niega &#8216;conexi\u00f3n mortal&#8217; con el narco"}]},{"@type":"WebSite","@id":"https:\/\/expresorgv.online\/home\/#website","url":"https:\/\/expresorgv.online\/home\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expresorgv.online\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/expresorgv.online\/home\/#\/schema\/person\/ae1ed1a575540204b5f59dca7f91f6a2","name":"expreso","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/88cd9f065dcd1b722cd984aac4181386a800c0bca699eaf07e42dd8f820bddee?s=96&d=mm&r=g","caption":"expreso"},"url":"https:\/\/expresorgv.online\/home\/blog\/author\/expreso\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/expresorgv.online\/home\/wp-content\/uploads\/2026\/07\/15072026Sedena.png?fit=540%2C300&ssl=1","_links":{"self":[{"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/posts\/36748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/comments?post=36748"}],"version-history":[{"count":1,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/posts\/36748\/revisions"}],"predecessor-version":[{"id":36749,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/posts\/36748\/revisions\/36749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/media\/36745"}],"wp:attachment":[{"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/media?parent=36748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/categories?post=36748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expresorgv.online\/home\/wp-json\/wp\/v2\/tags?post=36748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}